{"id":27095,"date":"2024-08-29T09:13:16","date_gmt":"2024-08-29T07:13:16","guid":{"rendered":"https:\/\/www.discoverypublisher.com\/fr\/?page_id=27095"},"modified":"2024-09-02T09:44:49","modified_gmt":"2024-09-02T07:44:49","slug":"adi-shankaracarya","status":"publish","type":"page","link":"https:\/\/www.discoverypublisher.com\/fr\/personnalites\/adi-shankaracarya","title":{"rendered":"\u00c2di Shankar\u00e2c\u00e2rya"},"content":{"rendered":"<p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full-width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;15&#8243;][vc_column][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Shankar\u00e2c\u00e2rya : le ma\u00eetre de la non dualite. Le nom du philosophe indien \u00c2di Shankar\u00e2c\u00e2rya suscite partout en Inde et dans le reste du monde, un grand respect qui s&#8217;adresse \u00e0 la fois \u00e0 la gloire spirituelle du ma\u00eetre, \u00e0 sa perfection po\u00e9tique et litt\u00e9raire, \u00e0 sa ferveur d\u00e9votionnelle et \u00e0 sa profondeur philosophique. Shankara est le philosophe qui a mis l&#8217;Advaita Ved\u00e2nta sous sa forme finale et il est \u00e0 ce titre consid\u00e9r\u00e9 comme le ma\u00eetre de la Non-dualit\u00e9.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full-width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;47&#8243;][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<h3>Naissance et enfance de Shankara<\/h3>\n<p>[\/vc_column_text][vc_separator type=&#8221;transparent&#8221; up=&#8221;15&#8243; down=&#8221;0&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">L&#8217;histoire de la vie de Shankara est en partie bas\u00e9e sur la l\u00e9gende m\u00eame si certains \u00e9l\u00e9ments historiques sont disponibles.<\/p>\n<p style=\"text-align: justify;\">C&#8217;est au Kerala, \u00e9tat situ\u00e9 \u00e0 l&#8217;extr\u00eame sud de l&#8217;Inde, que naquit Shankara, dans un petit village appel\u00e9 K\u00e2ladi, au 8\u00e8 si\u00e8cle de notre \u00e8re.<\/p>\n<p style=\"text-align: justify;\">Les parents de Shankara, Shivaguru et Aryamba, \u00e9taient brahmanes et menaient une vie de stricte orthodoxie. Pour obtenir la gr\u00e2ce d&#8217;une descendance, ils accomplirent de s\u00e9v\u00e8res aust\u00e9rit\u00e9s et entreprirent un p\u00e8lerinage. Shiva Lui-m\u00eame, satisfait de leur d\u00e9votion, leur apparut mais leur imposa un choix : avoir un fils brillant, destin\u00e9 \u00e0 mourir jeune ou mettre au monde de nombreux enfants, peu intelligents mais assur\u00e9s d&#8217;une longue vie. Ils opt\u00e8rent pour la premi\u00e8re alternative.<\/p>\n<p style=\"text-align: justify;\">Ce choix pr\u00e9sida aux destin\u00e9es de Shankara, l&#8217;enfant prodige, qui, d\u00e8s sa plus tendre enfance, fit preuve d&#8217;une remarquable intelligence : avant l&#8217;\u00e2ge de cinq ans, il poss\u00e9dait d\u00e9j\u00e0 le sanskrit et avait lu les r\u00e9cits de la mythologie. Tr\u00e8s jeune, il quitta ses parents pour suivre l&#8217;enseignement dans un \u00ab gurukula \u00bb (\u00e9cole v\u00e9dique), \u00e9tudier les Veda et les principaux points de vue philosophiques traditionnels.<\/p>\n<p style=\"text-align: justify;\">A l&#8217;\u00e2ge de huit ans, il retourna dans la demeure familiale, aupr\u00e8s de sa m\u00e8re, devenue veuve. La maison familiale o\u00f9 Shankara est n\u00e9, selon la l\u00e9gende, existe toujours (photos ci-contre) : cette demeure typique de l&#8217;architecture traditionnelle du Kerala, abrite maintenant un centre de recherches indologiques, le CIF (Chinmaya International Foundation).<\/p>\n<p style=\"text-align: justify;\">De plus en plus attir\u00e9 par la voie asc\u00e9tique, il obtint l&#8217;autorisation maternelle de devenir un \u00ab sanny\u00e2s\u00een \u00bb (renon\u00e7ant), et partit alors \u00e0 la recherche d&#8217;un ma\u00eetre.<\/p>\n<p style=\"text-align: justify;\">Un r\u00eave lui indiqua la pr\u00e9sence \u00e0 Omkarnath (Himalaya) d&#8217;un grand ma\u00eetre, Govinda Bhagavatp\u00e2da. Il s&#8217;y rendit et se prosterna devant l&#8217;asc\u00e8te qui l&#8217;accepta comme disciple.<\/p>\n<p style=\"text-align: justify;\">Pendant deux ans, Govinda lui enseigna la teneur des \u00ab Mah\u00e2v\u00e2kya \u00bb, les grandes d\u00e9clarations des Upanishad, et ensuite il le mena aupr\u00e8s de son propre ma\u00eetre, Gaudapada, avec qui Shankara v\u00e9cut plusieurs ann\u00e9es. Le jeune homme acquit aupr\u00e8s de ses ma\u00eetres une ma\u00eetrise totale des Ecritures et atteignit l&#8217;exp\u00e9rience ultime, l&#8217;union avec le Soi.<\/p>\n<p style=\"text-align: justify;\">Puis son ma\u00eetre lui demanda de se rendre \u00e0 Kashi (B\u00e9nar\u00e9s), pour y r\u00e9diger un commentaire des grands textes de base du Ved\u00e2nta que sont les Upanishad, les Brahma S\u00fbtra et la Bhagavad G\u00eet\u00e2.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_separator type=&#8221;transparent&#8221; up=&#8221;10&#8243;][vc_single_image image=&#8221;27125&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_rounded&#8221; qode_css_animation=&#8221;element_from_left&#8221; transition_delay=&#8221;0.3&#8243;][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full-width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;47&#8243;][vc_column width=&#8221;1\/3&#8243;][vc_separator type=&#8221;transparent&#8221; up=&#8221;10&#8243;][vc_single_image image=&#8221;27119&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_rounded&#8221; qode_css_animation=&#8221;element_from_left&#8221; transition_delay=&#8221;0.3&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<h3 class=\"p1\" style=\"text-align: justify;\">Shankara \u00e0 B\u00e9nar\u00e9s (Kashi)<\/h3>\n<p>[\/vc_column_text][vc_separator type=&#8221;transparent&#8221; up=&#8221;15&#8243; down=&#8221;0&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">B\u00e9nar\u00e9s (Kashi) \u00e9tait alors le centre de la pens\u00e9e philosophique o\u00f9 se rencontraient les \u00e9rudits de toutes les \u00e9coles, lieu de r\u00e9f\u00e9rence par lequel devait passer toute doctrine avant de pouvoir se r\u00e9pandre. Shankara s&#8217;y \u00e9tablit en compagnie de quelques disciples. Malgr\u00e9 son extr\u00eame jeunesse, il s&#8217;imposait \u00e0 tous, sages et lettr\u00e9s, car nul ne pouvait se mesurer \u00e0 sa vaste \u00e9rudition et \u00e0 sa force d&#8217;argumentation.<\/p>\n<p style=\"text-align: justify;\">La religion hindoue est en essence un monisme : selon la tradition v\u00e9dique ancienne, dont est issue l&#8217;actuelle forme de l\u2019hindouisme, un Principe supr\u00eame unique, brahman, est la source et la r\u00e9alit\u00e9 du monde que nous percevons, il est aussi l&#8217;essence de notre \u00eatre. Mais l\u2019homme g\u00e9n\u00e9ralement ne peut adorer une entit\u00e9 abstraite, et il projette des formes qui sourient \u00e0 son coeur : la multiplicit\u00e9 des formes divines que l&#8217;on rencontre en Inde traduit la multiplicit\u00e9 des mani\u00e8res dont les hommes aiment, d\u00e9sirent, craignent, esp\u00e8rent et vivent.<\/p>\n<p style=\"text-align: justify;\">Cependant, l&#8217;homme oublie parfois la R\u00e9alit\u00e9 supr\u00eame qui donne vie et sens \u00e0 ces noms et formes : sans ce sentiment d&#8217;unit\u00e9, les rites perdent de leur signification, les adorateurs de telle ou telle divinit\u00e9 en viennent \u00e0 s&#8217;opposer.<\/p>\n<p style=\"text-align: justify;\">Telle \u00e9tait la situation \u00e0 l&#8217;\u00e9poque de Shankara, au 8\u00e8 si\u00e8cle de notre \u00e8re. La pratique de la culture v\u00e9dique \u00e9tait alors en voie de totale d\u00e9sint\u00e9gration alors que l&#8217;influence du bouddhisme ne cessait de grandir.<\/p>\n<p style=\"text-align: justify;\">Shankara entreprit de raviver la vision non dualiste, de secouer l&#8217;\u00e9tat d&#8217;ignorance, de bigoterie, de rivalit\u00e9s sectaires o\u00f9 s&#8217;enlisait la religion hindoue. Il affronta la situation avec la plus subtile des strat\u00e9gies, attaquant le probl\u00e8me sur tous les fronts \u00e0 la fois : intellectuel, \u00e9motionnel et physique.<\/p>\n<p style=\"text-align: justify;\">Les d\u00e9bats philosophiques \u00e9taient fr\u00e9quents \u00e0 B\u00e9nar\u00e9s, d&#8217;autant plus que les rivalit\u00e9s entre les diff\u00e9rentes \u00e9coles de pens\u00e9e \u00e9taient constantes et tr\u00e8s vives.<\/p>\n<p style=\"text-align: justify;\">Parmi ces \u00e9coles, celle du P\u00fbrva Mim\u00e2ms\u00e2 occupait une place pr\u00e9pond\u00e9rante. Interpr\u00e9tant le Veda dans un sens ritualiste, ses ma\u00eetres r\u00e9futant l&#8217;existence d&#8217;un Principe Divin supr\u00eame. Shankara voulut un jour rencontrer un de ces grands ma\u00eetres. Le d\u00e9bat dura six jours au bout desquels le \u00ab m\u00eem\u00e2msaka \u00bb (partisan du mim\u00e2ms\u00e2) dut s\u2019avouer vaincu devant l&#8217;implacable logique de l&#8217;argumentation d\u00e9ploy\u00e9e par Shankara. Suite \u00e0 ces d\u00e9bats, la renomm\u00e9e de Shankara s&#8217;\u00e9tendit, beaucoup voyant en lui un nouveau leader venu revitaliser l&#8217;hindouisme.<\/p>\n<p style=\"text-align: justify;\">Pendant le reste de sa vie, Shankara voyagea dans toute l&#8217;Inde, visitant les grands temples, les lieux de p\u00e8lerinage, enseignant la voie de l\u2019Advaita Ved\u00e2nta (pens\u00e9e non-dualiste). Son rayonnement spirituel attir\u00e8rent vers lui de grands disciples qui continu\u00e8rent son oeuvre.<\/p>\n<p style=\"text-align: justify;\">La fa\u00e7on dont Shankara quitta ce monde est entour\u00e9e de myst\u00e8re. Selon la l\u00e9gende, il disparut un jour dans l&#8217;Himalaya.<\/p>\n<p style=\"text-align: justify;\">Shankara avait une mission \u00e0 laquelle il consacra sa vie : guider les hommes sur le chemin de la Connaissance. Pour cela, il fut \u00e0 la fois \u00e9crivain, enseignant et r\u00e9formateur religieux.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full-width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;47&#8243;][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<h3>Shankara \u00e9crivain et commentateur des textes<\/h3>\n<p>[\/vc_column_text][vc_separator type=&#8221;transparent&#8221; up=&#8221;15&#8243; down=&#8221;0&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Shankara \u00e9crivit des commentaires sur les dix principales Upanishad, sur les Brahma S\u00fbtra et la Bhagavad G\u00eet\u00e2, qui restent encore in\u00e9gal\u00e9s aujourd&#8217;hui. Avec une logique implacable, il y reprend un par un les arguments des \u00e9coles (en particulier bouddhistes) qui r\u00e9futaient l&#8217;existence de l\u2019\u00e2tman (la Conscience pure, le Soi), et affirme que cette r\u00e9alit\u00e9 supr\u00eame ne peut \u00eatre connue que par l&#8217;exp\u00e9rience intuitive.<\/p>\n<p style=\"text-align: justify;\">Dans ses \u00e9crits, Shankara non seulement d\u00e9livre avec logique et profondeur la vision de la Non-dualit\u00e9, mais il donne des instructions d\u00e9taill\u00e9es sur la discipline spirituelle. Il expose les pratiques permettant de pr\u00e9parer l&#8217;esprit \u00e0 l&#8217;accomplissement spirituel &#8211; l&#8217;Eveil &#8211; qui n&#8217;est pas un r\u00e9sultat \u00e0 obtenir, mais un \u00e9tat \u00e9ternellement pr\u00e9sent \u00e0 r\u00e9v\u00e9ler.<\/p>\n<p style=\"text-align: justify;\">Dans son commentaire des Brahma S\u00fbtra, il s&#8217;en prend aussi aux tenants du Mim\u00e2ms\u00e2, qui n&#8217;accordaient d&#8217;importance qu&#8217;\u00e0 la portion ritualiste des Veda, et consid\u00e9raient les Upanishad comme secondaires. Selon eux, la lib\u00e9ration spirituelle ne pouvait \u00eatre atteinte que par l&#8217;accomplissement de c\u00e9r\u00e9monies et de rituels.<\/p>\n<p style=\"text-align: justify;\">Contestant leur th\u00e8se, Shankara d\u00e9veloppe les aspects fondamentaux du Ved\u00e2nta avec sa logique parfaite et ses exemples concrets.<\/p>\n<p style=\"text-align: justify;\">Il composa aussi des textes d&#8217;introduction (prakara grantha) o\u00f9 il explique avec une grande clart\u00e9 et beaucoup de po\u00e9sie la vision de l\u2019Advaita : Tattva Bodha, \u00c2tma Bodha, Vivekac\u00fbd\u00e2mani, Bhaja Govindam\u2026<\/p>\n<p style=\"text-align: justify;\">Sa prodigieuse connaissance des \u00c9critures et son rayonnement spirituel attiraient autour de lui des auditoires toujours plus nombreux : aux d\u00e9vots de Shiva, de Vishnu, de la Dev\u00ee, aux \u00e9rudits, aux pr\u00eatres, il parlait de l\u2019\u00catre Unique, r\u00e9v\u00e9l\u00e9 sous de multiples formes.<br \/>\n&lt;h3&gt;Shankara : une oeuvre de r\u00e9formateur religieux&lt;\/h3&gt;<br \/>\nApr\u00e8s ces conqu\u00eates intellectuelles, Shankara voulut entra\u00eener les masses : cela ne pouvait se faire que par une approche d\u00e9votionnelle. En effet, les partisans des dieux Shiva, Vishnu, de la Dev\u00ee (la d\u00e9esse), se querellaient, d\u00e9fendant tous la supr\u00e9matie de leur divinit\u00e9. Il fallait les ramener au sein de la vision non dualiste, leur source commune et r\u00e9tablir l&#8217;harmonie entre eux en leur montrant qu&#8217;une V\u00e9rit\u00e9 Unique sous-tendait toutes les formes divines.<\/p>\n<p style=\"text-align: justify;\">Il composa plus de soixante hymnes d\u00e9votionnels (stotra) en l&#8217;honneur des diff\u00e9rentes divinit\u00e9s, chants tr\u00e8s m\u00e9lodieux, aux paroles pleines d&#8217;\u00e9l\u00e9vation, charg\u00e9es de ferveur d\u00e9votionnelle, qui, au-del\u00e0 de la forme ador\u00e9e, s&#8217;adressent au Brahman Supr\u00eame. Ces hymnes sont tr\u00e8s populaires en Inde et ils sont chant\u00e9s quotidiennement dans les temples et les foyers.<\/p>\n<p style=\"text-align: justify;\">Shankara entreprit aussi une oeuvre de r\u00e9formateur : l&#8217;hindouisme s&#8217;\u00e9tant entach\u00e9 de nombreuses h\u00e9r\u00e9sies, il les combattit avec vigueur et voulut r\u00e9tablir le sens du rituel, qui doit \u00eatre avant tout int\u00e9rieur. Les offrandes ne sont que le symbole du sacrifice de l&#8217;\u00e2me. Il codifia \u00e9galement les cultes offerts aux diff\u00e9rentes divinit\u00e9s, afin de leur apporter une certaine unit\u00e9 de sens.<\/p>\n<p style=\"text-align: justify;\">Shankara entreprit aussi consolidation physique de ce renouveau en \u00e9tablissant des temples d\u00e9di\u00e9s aux diff\u00e9rentes divinit\u00e9s dans toute l&#8217;Inde. Il cr\u00e9a \u00e9galement des ordres asc\u00e9tiques (les math) aux quatre coins de l&#8217;Inde : Jyotir Math \u00e0 Badari au Nord, Dwaraka \u00e0 l&#8217;ouest, Puri \u00e0 l&#8217;est, Shringeri au sud. Ces monast\u00e8res, o\u00f9 devait \u00eatre enseign\u00e9e la Tradition \u00e0 travers l&#8217;\u00e9tude des Veda, devaient \u00eatre dirig\u00e9s par une lign\u00e9e de ma\u00eetres spirituels, dont les premiers furent quatre grands disciples de Shankara. Ils restent de nos jours de hauts lieux de la philosophie de Shankara et les garants de la plus pure tradition advaitine.<\/p>\n<p style=\"text-align: justify;\">Enfin, Shankara d\u00e9finit aussi 10 cat\u00e9gories de leaders spirituels, qui firent all\u00e9geance aux math : ce sont leurs titres qui indiquent \u00e0 quel math les sanny\u00e2s\u00eens (moines) sont rattach\u00e9s. Ainsi, les sanny\u00e2s\u00eens rattach\u00e9s au math de Shringeri portent le titre de &#8220;Sarasvati&#8221;: c\u2019est le cas de tous les swamis de la Chinmaya Mission, puisque Swami Chinmayananda a re\u00e7u le sanny\u00e2sa de Swami Shivananda, qui \u00e9tait lui-m\u00eame rattach\u00e9 \u00e0 Shringeri. Son nom titre et son titre sont donc : Swami Chinmayananda Sarasvati.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_separator type=&#8221;transparent&#8221; up=&#8221;10&#8243;][vc_single_image image=&#8221;27120&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_rounded&#8221; qode_css_animation=&#8221;element_from_left&#8221; transition_delay=&#8221;0.3&#8243;][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full-width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; padding_top=&#8221;47&#8243;][vc_column width=&#8221;1\/3&#8243;][vc_separator type=&#8221;transparent&#8221; up=&#8221;10&#8243;][vc_single_image image=&#8221;27121&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_rounded&#8221; qode_css_animation=&#8221;element_from_left&#8221; transition_delay=&#8221;0.3&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<h3 class=\"p1\" style=\"text-align: justify;\">Citations de Shankara<\/h3>\n<p>[\/vc_column_text][vc_separator type=&#8221;transparent&#8221; up=&#8221;15&#8243; down=&#8221;0&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">C&#8217;est dans ce texte que se trouve la c\u00e9l\u00e8bre d\u00e9claration de Shankara :<\/p>\n<blockquote><p>brahma satyam jaganmithy\u00e2 jIvo brahmaiva n\u00e2parah<br \/>\nanena vedyam sacch\u00e2stram iti ved\u00e2ntadindimah-20<\/p>\n<p>\u00ab Brahman est r\u00e9el, l\u2019univers est une apparence illusoire (mithya), l\u2019individu (j\u00eeva) n\u2019est pas different du Brahman. Ceci doit \u00eatre compris comme la declaration scirupturale juste. C\u2019est ce que proclame le Ved\u00e2nta. \u00bb<\/p><\/blockquote>\n<p style=\"text-align: justify;\"><em>Bhaja Govindam, verset 4<\/em><\/p>\n<blockquote><p>\u00ab La goutte d&#8217;eau vacillant sur le p\u00e9tale de lotus a une existence extr\u00eamement incertaine. La vie est aussi incertaine. Comprends \u00e0 quel point ce monde est d\u00e9vor\u00e9 parla maladie et la vanit\u00e9 et entach\u00e9 de souffrances. \u00bb<\/p><\/blockquote>\n<p style=\"text-align: justify;\"><em>Vivekacud\u00e2mani<\/em><\/p>\n<blockquote><p>\u00ab Cette R\u00e9alit\u00e9 Unique, qui appara\u00eet de fa\u00e7on vari\u00e9e du fait de l\u2019illusion &#8211; bien qu\u2019Elle-m\u00eame soit toujours inchang\u00e9e &#8211; et qui assume des noms et des formes, des attributs et des changements, comme l\u2019or \u00e0 travers toutes ses modifications &#8211; ce Brahman tu es. M\u00e9dite cela en ton esprit. \u00bb<\/p>\n<p>\u00ab Celui qui ressent une profonde d\u00e9votion pour les Ecritures (Shruti), qui est \u00e9tabli dans son Svadharma (devoir personnel) &#8211; car cela seulement peut contribuer \u00e0 purifier le mental &#8211; et qui poss\u00e8de un mental pur, r\u00e9alise le Soi supr\u00eame. Seule cette connaissance permet de d\u00e9truire le sams\u00e2ra (cycle des naissances et des morts), racine et branche. \u00bb<\/p>\n<p>\u00ab La lib\u00e9ration vient d\u2019abord d\u2019un extr\u00eame d\u00e9tachement \u00e0 l\u2019\u00e9gard des objets limit\u00e9s, source de satisfaction sensuelle. Puis viennent ensuite le calme, la ma\u00eetrise de soi, la patience (l\u2019endurance),et un complet renoncement aux actions \u00e9go\u00efstes. \u00bb<\/p>\n<p>\u00ab Ensuite, viennent \u201cl\u2019\u00e9coute\u201d (de l\u2019enseignement), la r\u00e9flexion sur ce qui a \u00e9t\u00e9 entendu et enfin, la contemplation longue, constante et continue sur la V\u00e9rit\u00e9, pour l\u2019adepte qui pratique cette m\u00e9ditation (muni). Finalement, cet \u00eatre avis\u00e9 atteint l\u2019\u00e9tat supr\u00eame de \u201cnirvikalpa\u201d et r\u00e9alise la b\u00e9atitude du \u201cnirvana\u201d dans cette vie m\u00eame. \u00bb<\/p><\/blockquote>\n<p style=\"text-align: justify;\"><em>Vakya Vritti<\/em><\/p>\n<blockquote><p>\u00ab Je suis Cela, la Conscience unique, qui est le Soi illuminant les modifications de mon mental telles que : \u201cmon mental est agit\u00e9, mon mental est calme, etc.\u201d Je suis Cela. \u00bb<\/p>\n<p>\u00ab Je suis Cela, la Conscience unique qui est le Soi \u00e9ternel qui est connu directement, qui illumine les trois \u00e9tats de veille, de r\u00eave, et de sommeil profond, et qui illumine les apparitions et disparitions de l\u2019intellect et ses fonctions. Je suis Cela. \u00bb<\/p><\/blockquote>\n<p style=\"text-align: justify;\"><em>Atma bodha<\/em><\/p>\n<blockquote><p>\u00ab Comme des bulles dans l\u2019eau, les mondes naissent, existent et se dissolvent dans le Soi, qui est la cause mat\u00e9rielle et le support de toute chose. \u00bb <em>Commentaire des Brahma S\u00fbtra (III, 4, 52)<\/em><\/p>\n<p>\u00ab La d\u00e9livrance n\u2019est pas quelque chose \u00e0 accomplir, mais quelque chose d\u2019\u00e9ternellement accompli, \u00e0 quoi la Connaissance donne acc\u00e8s. \u00bb&nbsp;<em>Commentaire de la Brihad\u00e2ranyaka Upanishad (II, 1, 20)<\/em><\/p>\n<p>\u00abDans les Upanishads, la notion d\u2019un Brahman s\u2019attelant aux t\u00e2ches de cr\u00e9ation, de maintien, et de dissolution de l\u2019univers est pr\u00e9sent\u00e9e dans le seul but de fortifier dans l\u2019\u00e2me du disciple la conviction de son identit\u00e9 au Brahman, et non pas d\u2019affirmer la r\u00e9alit\u00e9 du processus cosmogonique.\u00bb<\/p><\/blockquote>\n<p style=\"text-align: justify;\">Citations extraites des commentaires de Swami Chinmayananda.<\/p>\n<p style=\"text-align: justify;\"><em>Source : \u00ab Shankara the missionnary \u00bb, par Swami Chinmayananda &#8211; Editions CCMT (Central Chinmaya Mission Trust &#8211; Mumbai)<\/em><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; background_color=&#8221;#ffffff&#8221; padding_top=&#8221;47&#8243;][vc_column][vc_column_text]<\/p>\n<p><div class=\"ngg-galleria-parent nextgen_pro_horizontal_filmstrip\"\n     data-id=\"0f9182a5055c889545086d7b2685bcfd\"\n     id=\"displayed_gallery_0f9182a5055c889545086d7b2685bcfd\">\n\t<div class=\"ngg-galleria\"><\/div>\n\n    <div class=\"ngg-galleria-offscreen-seo-wrapper\">\n                    <a href=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/benares.jpg\"\n               title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/benares.jpg\"\n               data-thumbnail=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/thumbs\/thumbs_benares.jpg\"\n               data-image-id=\"1278\"\n               data-title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-description=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n                class=\"ngg-fancybox\" rel=\"0f9182a5055c889545086d7b2685bcfd\">\n                <picture>\n\t\n<source srcset='https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/benares.jpg' media=''>\n<img title=\"\u00c2di Shankar\u00e2c\u00e2rya\" alt=\"\u00c2di Shankar\u00e2c\u00e2rya\" width=\"360\" height=\"239\" style=\"max-width:360px;max-height:239px\" src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/benares.jpg\" srcset=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/benares.jpg\" onerror=\"nggRetryFailedImage(this);\"\/>\n<\/picture>            <\/a>\n                        <a href=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Shankara-et-disciples2.jpg\"\n               title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Shankara-et-disciples2.jpg\"\n               data-thumbnail=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/thumbs\/thumbs_Shankara-et-disciples2.jpg\"\n               data-image-id=\"1279\"\n               data-title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-description=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n                class=\"ngg-fancybox\" rel=\"0f9182a5055c889545086d7b2685bcfd\">\n                <picture>\n\t\n<source srcset='https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Shankara-et-disciples2.jpg' media=''>\n<img title=\"\u00c2di Shankar\u00e2c\u00e2rya\" alt=\"\u00c2di Shankar\u00e2c\u00e2rya\" width=\"472\" height=\"342\" style=\"max-width:472px;max-height:342px\" src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Shankara-et-disciples2.jpg\" srcset=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Shankara-et-disciples2.jpg\" onerror=\"nggRetryFailedImage(this);\"\/>\n<\/picture>            <\/a>\n                        <a href=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-bibliotheque.jpg\"\n               title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-bibliotheque.jpg\"\n               data-thumbnail=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/thumbs\/thumbs_shankara-CIF-bibliotheque.jpg\"\n               data-image-id=\"1280\"\n               data-title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-description=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n                class=\"ngg-fancybox\" rel=\"0f9182a5055c889545086d7b2685bcfd\">\n                <picture>\n\t\n<source srcset='https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-bibliotheque.jpg' media=''>\n<img title=\"\u00c2di Shankar\u00e2c\u00e2rya\" alt=\"\u00c2di Shankar\u00e2c\u00e2rya\" width=\"510\" height=\"358\" style=\"max-width:510px;max-height:358px\" src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-bibliotheque.jpg\" srcset=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-bibliotheque.jpg\" onerror=\"nggRetryFailedImage(this);\"\/>\n<\/picture>            <\/a>\n                        <a href=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Ecritures1.jpg\"\n               title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Ecritures1.jpg\"\n               data-thumbnail=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/thumbs\/thumbs_Ecritures1.jpg\"\n               data-image-id=\"1281\"\n               data-title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-description=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n                class=\"ngg-fancybox\" rel=\"0f9182a5055c889545086d7b2685bcfd\">\n                <picture>\n\t\n<source srcset='https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Ecritures1.jpg' media=''>\n<img title=\"\u00c2di Shankar\u00e2c\u00e2rya\" alt=\"\u00c2di Shankar\u00e2c\u00e2rya\" width=\"425\" height=\"283\" style=\"max-width:425px;max-height:283px\" src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Ecritures1.jpg\" srcset=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Ecritures1.jpg\" onerror=\"nggRetryFailedImage(this);\"\/>\n<\/picture>            <\/a>\n                        <a href=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-1.jpg\"\n               title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-1.jpg\"\n               data-thumbnail=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/thumbs\/thumbs_shankara-CIF-1.jpg\"\n               data-image-id=\"1282\"\n               data-title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-description=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n                class=\"ngg-fancybox\" rel=\"0f9182a5055c889545086d7b2685bcfd\">\n                <picture>\n\t\n<source srcset='https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-1.jpg' media=''>\n<img title=\"\u00c2di Shankar\u00e2c\u00e2rya\" alt=\"\u00c2di Shankar\u00e2c\u00e2rya\" width=\"510\" height=\"358\" style=\"max-width:510px;max-height:358px\" src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-1.jpg\" srcset=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-1.jpg\" onerror=\"nggRetryFailedImage(this);\"\/>\n<\/picture>            <\/a>\n                        <a href=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-2.jpg\"\n               title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-2.jpg\"\n               data-thumbnail=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/thumbs\/thumbs_shankara-CIF-2.jpg\"\n               data-image-id=\"1283\"\n               data-title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-description=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n                class=\"ngg-fancybox\" rel=\"0f9182a5055c889545086d7b2685bcfd\">\n                <picture>\n\t\n<source srcset='https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-2.jpg' media=''>\n<img title=\"\u00c2di Shankar\u00e2c\u00e2rya\" alt=\"\u00c2di Shankar\u00e2c\u00e2rya\" width=\"510\" height=\"358\" style=\"max-width:510px;max-height:358px\" src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-2.jpg\" srcset=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-CIF-2.jpg\" onerror=\"nggRetryFailedImage(this);\"\/>\n<\/picture>            <\/a>\n                        <a href=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-kerala.jpg\"\n               title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-kerala.jpg\"\n               data-thumbnail=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/thumbs\/thumbs_shankara-kerala.jpg\"\n               data-image-id=\"1284\"\n               data-title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-description=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n                class=\"ngg-fancybox\" rel=\"0f9182a5055c889545086d7b2685bcfd\">\n                <picture>\n\t\n<source srcset='https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-kerala.jpg' media=''>\n<img title=\"\u00c2di Shankar\u00e2c\u00e2rya\" alt=\"\u00c2di Shankar\u00e2c\u00e2rya\" width=\"350\" height=\"262\" style=\"max-width:350px;max-height:262px\" src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-kerala.jpg\" srcset=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-kerala.jpg\" onerror=\"nggRetryFailedImage(this);\"\/>\n<\/picture>            <\/a>\n                        <a href=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara2.jpg\"\n               title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara2.jpg\"\n               data-thumbnail=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/thumbs\/thumbs_shankara2.jpg\"\n               data-image-id=\"1285\"\n               data-title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-description=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n                class=\"ngg-fancybox\" rel=\"0f9182a5055c889545086d7b2685bcfd\">\n                <picture>\n\t\n<source srcset='https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara2.jpg' media=''>\n<img title=\"\u00c2di Shankar\u00e2c\u00e2rya\" alt=\"\u00c2di Shankar\u00e2c\u00e2rya\" width=\"280\" height=\"322\" style=\"max-width:280px;max-height:322px\" src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara2.jpg\" srcset=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara2.jpg\" onerror=\"nggRetryFailedImage(this);\"\/>\n<\/picture>            <\/a>\n                        <a href=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Siva_Markandeya_Purana.jpg\"\n               title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Siva_Markandeya_Purana.jpg\"\n               data-thumbnail=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/thumbs\/thumbs_Siva_Markandeya_Purana.jpg\"\n               data-image-id=\"1286\"\n               data-title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-description=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n                class=\"ngg-fancybox\" rel=\"0f9182a5055c889545086d7b2685bcfd\">\n                <picture>\n\t\n<source srcset='https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Siva_Markandeya_Purana.jpg' media=''>\n<img title=\"\u00c2di Shankar\u00e2c\u00e2rya\" alt=\"\u00c2di Shankar\u00e2c\u00e2rya\" width=\"689\" height=\"152\" style=\"max-width:689px;max-height:152px\" src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Siva_Markandeya_Purana.jpg\" srcset=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/Siva_Markandeya_Purana.jpg\" onerror=\"nggRetryFailedImage(this);\"\/>\n<\/picture>            <\/a>\n                        <a href=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-temple-inde-sud.jpg\"\n               title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-temple-inde-sud.jpg\"\n               data-thumbnail=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/thumbs\/thumbs_shankara-temple-inde-sud.jpg\"\n               data-image-id=\"1287\"\n               data-title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-description=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n                class=\"ngg-fancybox\" rel=\"0f9182a5055c889545086d7b2685bcfd\">\n                <picture>\n\t\n<source srcset='https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-temple-inde-sud.jpg' media=''>\n<img title=\"\u00c2di Shankar\u00e2c\u00e2rya\" alt=\"\u00c2di Shankar\u00e2c\u00e2rya\" width=\"384\" height=\"512\" style=\"max-width:384px;max-height:512px\" src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-temple-inde-sud.jpg\" srcset=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-temple-inde-sud.jpg\" onerror=\"nggRetryFailedImage(this);\"\/>\n<\/picture>            <\/a>\n                        <a href=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-trimurti.jpg\"\n               title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-trimurti.jpg\"\n               data-thumbnail=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/thumbs\/thumbs_shankara-trimurti.jpg\"\n               data-image-id=\"1288\"\n               data-title=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n               data-description=\"\u00c2di Shankar\u00e2c\u00e2rya\"\n                class=\"ngg-fancybox\" rel=\"0f9182a5055c889545086d7b2685bcfd\">\n                <picture>\n\t\n<source srcset='https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-trimurti.jpg' media=''>\n<img title=\"\u00c2di Shankar\u00e2c\u00e2rya\" alt=\"\u00c2di Shankar\u00e2c\u00e2rya\" width=\"474\" height=\"709\" style=\"max-width:474px;max-height:709px\" src=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-trimurti.jpg\" srcset=\"https:\/\/www.discoverypublisher.com\/fr\/wp-content\/uploads\/sites\/1\/nggallery\/shankaracarya\/shankara-trimurti.jpg\" onerror=\"nggRetryFailedImage(this);\"\/>\n<\/picture>            <\/a>\n                <\/div>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text]<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221; background_color=&#8221;#ffffff&#8221; padding_top=&#8221;47&#8243;][vc_column][vc_separator type=&#8221;transparent&#8221; down=&#8221;84&#8243;][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text]<\/p>\n<p>&nbsp;[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le nom du philosophe indien \u00c2di Shankar\u00e2c\u00e2rya suscite partout en Inde et dans le reste du monde, un grand respect qui s&#8217;adresse \u00e0 la fois \u00e0 la gloire spirituelle du ma\u00eetre.<\/p>\n","protected":false},"author":1,"featured_media":27098,"parent":23409,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","ngg_post_thumbnail":0},"tags":[9420,9045,9947,9416,9989,9949,10182],"_links":{"self":[{"href":"https:\/\/www.discoverypublisher.com\/fr\/wp-json\/wp\/v2\/pages\/27095"}],"collection":[{"href":"https:\/\/www.discoverypublisher.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.discoverypublisher.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.discoverypublisher.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.discoverypublisher.com\/fr\/wp-json\/wp\/v2\/comments?post=27095"}],"version-history":[{"count":10,"href":"https:\/\/www.discoverypublisher.com\/fr\/wp-json\/wp\/v2\/pages\/27095\/revisions"}],"predecessor-version":[{"id":27150,"href":"https:\/\/www.discoverypublisher.com\/fr\/wp-json\/wp\/v2\/pages\/27095\/revisions\/27150"}],"up":[{"embeddable":true,"href":"https:\/\/www.discoverypublisher.com\/fr\/wp-json\/wp\/v2\/pages\/23409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.discoverypublisher.com\/fr\/wp-json\/wp\/v2\/media\/27098"}],"wp:attachment":[{"href":"https:\/\/www.discoverypublisher.com\/fr\/wp-json\/wp\/v2\/media?parent=27095"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.discoverypublisher.com\/fr\/wp-json\/wp\/v2\/tags?post=27095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}